{"id":3716,"date":"2020-06-01T20:11:18","date_gmt":"2020-06-01T20:11:18","guid":{"rendered":"https:\/\/familylawyer-thehague.nl\/?p=3716"},"modified":"2023-01-06T20:26:50","modified_gmt":"2023-01-06T19:26:50","slug":"childrens-refusal-not-accepted","status":"publish","type":"post","link":"https:\/\/familylawyer-thehague.nl\/fr\/childrens-refusal-not-accepted\/","title":{"rendered":"Le \"refus\" des enfants n'est pas accept\u00e9"},"content":{"rendered":"<h3><strong>Tribunal de district de La Haye<\/strong><\/h3>\n<p><a href=\"https:\/\/uitspraken.rechtspraak.nl\/inziendocument?id=ECLI:NL:RBDHA:2020:2861\">26 mars 2020, ECLI:NL:RBDHA:2020:2861<\/a><\/p>\n<div><strong>Le tribunal ne voit aucun fondement pour le \"refus\", car la r\u00e9sistance des enfants r\u00e9sulte de l'image n\u00e9gative que le p\u00e8re a de la m\u00e8re et de leur d\u00e9pendance \u00e0 l'\u00e9gard du p\u00e8re. Le gardien ad litem a soutenu que les enfants et le p\u00e8re forment \"une \u00eele\" aux Pays-Bas. Selon elle, il existe une dissonance cognitive et une pression syst\u00e9mique. La cour pense que leur r\u00e9sistance n'est pas une raison pour refuser un retour imm\u00e9diat aux \u00c9tats-Unis.<\/strong><\/div>\n<h3><strong>La Convention<\/strong><\/h3>\n<div>Conform\u00e9ment \u00e0 la Convention de La Haye sur l'enl\u00e8vement d'enfants, le tribunal doit ordonner le retour imm\u00e9diat d'un enfant en cas de d\u00e9placement illicite ou de d\u00e9tention illicite (contrairement \u00e0 la garde conjointe). Si moins d'un an s'est \u00e9coul\u00e9 entre le transfert des enfants aux Pays-Bas, le tribunal ne se penchera pas sur la question de savoir si les enfants ont des racines aux Pays-Bas. Le tribunal ne peut renoncer \u00e0 une d\u00e9cision de retour que s'il existe un motif de refus tel que vis\u00e9 \u00e0 l'article 13 de la Convention.<\/div>\n<h3><strong>Les faits<\/strong><\/h3>\n<p>Les parties conviennent qu'elles ont la garde conjointe des enfants et qu'elles exercent effectivement cette garde. Elles conviennent \u00e9galement que les enfants avaient leur lieu de r\u00e9sidence habituel aux \u00c9tats-Unis imm\u00e9diatement avant leur transfert aux Pays-Bas. Il n'est pas non plus contest\u00e9 que le p\u00e8re n'a pas demand\u00e9 ou re\u00e7u l'autorisation de la m\u00e8re ou d'un tribunal de se rendre aux Pays-Bas et de s'y installer avec les enfants.<\/p>\n<h3><strong>Motif de refus<\/strong><\/h3>\n<div>\n<div>Le p\u00e8re pr\u00e9tend qu'il y a deux motifs de refus.<\/div>\n<div>1) A leur retour aux Etats-Unis, les enfants se trouveront dans une situation intol\u00e9rable au sens de l'article 13(1)(b) de la Convention.<\/div>\n<div>2) Il existe une opposition de la part des enfants au sens de l'article 13, paragraphe 2, de la Convention.<\/div>\n<h3><strong>Le p\u00e8re<\/strong><\/h3>\n<div>\n<div>Le p\u00e8re pr\u00e9tend que le lien entre la m\u00e8re et les enfants est mauvais. La m\u00e8re la tromp\u00e9 et les enfants ont de grandes difficult\u00e9s s'y faire id\u00e9e. Ces derniers mois, les enfants ont indiqu\u00e9 de mani\u00e8re ind\u00e9pendante et constante qu'ils souhaitaient rester avec le p\u00e8re aux Pays-Bas.<\/div>\n<div><\/div>\n<div>De plus, il ne peut pas et ne pourra pas revenir aux \u00c9tats-Unis pendant les dix prochaines ann\u00e9es. Cela signifie \u00e9galement que si les enfants sont renvoy\u00e9s, ils seront s\u00e9par\u00e9s de leur principale figure d'attachement : leur p\u00e8re.<\/div>\n<h3><strong>La m\u00e8re<\/strong><\/h3>\n<div>\n<div>La m\u00e8re d\u00e9clare que les enfants aux \u00c9tats-Unis \u00e9taient attach\u00e9s aux deux parents. Il y avait un accord de co-parentalit\u00e9. La relation avec les enfants est effectivement perturb\u00e9e et les enfants auront besoin d'aide lorsqu'ils retourneront aux \u00c9tats-Unis. Mais le p\u00e8re nourrit les enfants dans leur image n\u00e9gative de la m\u00e8re.<\/div>\n<div><\/div>\n<div>Selon la m\u00e8re, le p\u00e8re peut revenir aux \u00c9tats-Unis. De plus, la jurisprudence montre que le simple fait que les enfants soient s\u00e9par\u00e9s du parent ravisseur lors du retour ne signifie pas que le retour peut \u00eatre refus\u00e9.<\/div>\n<h3><strong>Tuteur ad litem<\/strong><\/h3>\n<\/div>\n<div>Le gardien ad litem des enfants a parl\u00e9 aux enfants et a r\u00e9dig\u00e9 un rapport. Les deux enfants les plus \u00e2g\u00e9s indiquent qu'ils se portent bien aux Pays-Bas et que les \u00c9tats-Unis sont un chapitre clos. Ils ont d\u00fb quitter les \u00c9tats-Unis parce que le p\u00e8re leur avait dit que la m\u00e8re essayait de s'assurer qu'ils ne reverraient pas le p\u00e8re. Selon elle, les enfants et le p\u00e8re forment une \u00eele aux Pays-Bas. Ils sont donc tr\u00e8s proches les uns des autres et ont par d\u00e9finition la m\u00eame opinion. Elle se demande si les enfants peuvent s'exprimer librement dans cette situation. Selon elle, il existe une dissonance cognitive et une pression syst\u00e9mique chez les enfants (surtout les deux plus \u00e2g\u00e9s).<\/div>\n<h3><strong>D\u00e9cision du tribunal de district de La Haye<\/strong><\/h3>\n<p>Le tribunal est d'avis que le motif de refus \"situation insupportable\" doit \u00eatre interpr\u00e9t\u00e9 de mani\u00e8re tr\u00e8s restrictive et ne peut \u00eatre respect\u00e9 que dans des situations tr\u00e8s extr\u00eames. Ce n'est pas le cas dans cette situation, selon le tribunal de district. Le retour des enfants aux \u00c9tats-Unis ne signifie pas n\u00e9cessairement qu'il n'y aura plus de contact entre le p\u00e8re et les enfants.<\/p>\n<div>La juridiction peut refuser d'ordonner le retour si elle constate que les enfants s'opposent au retour et qu'ils ont atteint un \u00e2ge et un degr\u00e9 de maturit\u00e9 qui justifient la prise en compte de leur point de vue. Le tribunal est d'avis qu'il n'y a pas d'opposition fond\u00e9e.  Les deux enfants les plus \u00e2g\u00e9s se sont entretenus avec les juges avant l'audience. Le tribunal constate que les enfants expriment des sentiments n\u00e9gatifs envers la m\u00e8re, qu'ils sont entr\u00e9s dans un grave conflit de loyaut\u00e9 et qu'ils semblent avoir opt\u00e9 pour le p\u00e8re dans cette situation tr\u00e8s difficile pour eux. Cependant, le tribunal pr\u00eate attention \u00e0 ce que le mandataire sp\u00e9cial (guardian ad litem) a precis\u00e9.<\/div>\n<p>La r\u00e9ticence des enfants au retour et l'attitude des enfants semblent \u00eatre motiv\u00e9es par l'image n\u00e9gative que le p\u00e8re a de la m\u00e8re et leur d\u00e9pendance \u00e0 l'\u00e9gard du p\u00e8re dans la situation actuelle. Pour cette raison, le tribunal ne peut pas attacher tant d'importance \u00e0 l'opinion des enfants que cela devrait conduire \u00e0 l'acceptation de la r\u00e9sistance et au rejet du retour. En outre, il ressort du rapport du mandataire sp\u00e9cial que les enfants ne semblent pas se sentir libres de s'exprimer.<\/p>\n<\/div>\n<h3><strong>Appel<\/strong><\/h3>\n<p>Le p\u00e8re a fait appel. La cour d'appel de La Haye a donn\u00e9 <a href=\"https:\/\/uitspraken.rechtspraak.nl\/inziendocument?id=ECLI:NL:GHDHA:2020:1025\">sa d\u00e9cision<\/a> le 13 mai 2020. La cour d'appel a \u00e9galement d\u00e9cid\u00e9 que les enfants doivent retourner aux \u00c9tats-Unis. En outre, la cour d'appel a d\u00e9cid\u00e9 que, si le p\u00e8re ne retourne pas lui-m\u00eame les enfants aux \u00c9tats-Unis, il doit remettre les enfants \u00e0 la m\u00e8re. Le p\u00e8re a fait valoir que cela n'est possible que s'il est clair que la m\u00e8re peut imm\u00e9diatement se rendre aux \u00c9tats-Unis avec les enfants.<\/p>\n<p>La cour d'appel a d\u00e9clar\u00e9 qu'il est conforme \u00e0 l'intention de la Convention que les enfants soient ramen\u00e9s \u00e0 leur situation ant\u00e9rieure et qu'une d\u00e9cision selon laquelle le p\u00e8re devrait remettre les enfants \u00e0 la m\u00e8re y contribuera. La raison en est que tant que les enfants seront avec le p\u00e8re et sous sa seule influence, ils subiront un grave conflit de loyaut\u00e9. En outre, le fait que le p\u00e8re ait retir\u00e9 les enfants \u00e0 la garde de la m\u00e8re \u00e0 plusieurs reprises est \u00e9galement une raison pour la cour d'appel de d\u00e9cider que si le p\u00e8re n'am\u00e8ne pas lui-m\u00eame les enfants aux \u00c9tats-Unis, il doit les remettre \u00e0 la m\u00e8re.<\/p>\n<div>\n<h3><strong>Qu'est-ce que cela signifie pour les autres parents ?<\/strong><\/h3>\n<p>Ce cas montre \u00e0 quel point il est dommageable que les enfants soient isol\u00e9s et d\u00e9pendent de l'un de leurs parents. Non seulement les parents devraient en tirer une le\u00e7on, mais aussi l'environnement social des enfants dans le pays o\u00f9 ils ont \u00e9t\u00e9 enlev\u00e9s. Ils peuvent aider \u00e0 pr\u00e9venir l'isolement et \u00e0 maintenir le lien avec l'autre parent.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Vous pouvez lire plus d'informations sur <strong>enl\u00e8vement international d'enfants<\/strong>:<\/p>\n<p><a href=\"https:\/\/carefulchildrelocation.com\/\">www.carefulchildrelocation.com<\/a><\/p>\n<div>\n<div>Ou lisez notre <a href=\"https:\/\/familylawyer-thehague.nl\/fr\/encyclopedia\/category\/international-child-abduction-a-z\/\">A-Z<\/a>notre <a href=\"https:\/\/familylawyer-thehague.nl\/fr\/international-child-abduction-faq\/\">FAQ<\/a> ou notre page sur <a href=\"https:\/\/familylawyer-thehague.nl\/fr\/international-child-abduction\/\">enl\u00e8vement international d'enfants<\/a>.<\/div>\n<h2><\/h2>\n<div><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>District Court of The Hague March 26 2020, ECLI:NL:RBDHA:2020:2861 The court does not see any ground for &#8216;refusal&#8217;, because the children&#8217;s resistance is the result of the negative image father has of mother and their dependence on father. The Guardian ad litem had repported that the children and the father form &#8216;an island&#8217; in the [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[38],"tags":[60],"class_list":["post-3716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-law","tag-international-child-abduction"],"_links":{"self":[{"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/posts\/3716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/comments?post=3716"}],"version-history":[{"count":0,"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/posts\/3716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/media\/4214"}],"wp:attachment":[{"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/media?parent=3716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/categories?post=3716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/familylawyer-thehague.nl\/fr\/wp-json\/wp\/v2\/tags?post=3716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}